{"id":1259,"date":"2021-01-14T11:31:50","date_gmt":"2021-01-14T11:31:50","guid":{"rendered":"http:\/\/etoropartners.wpengine.com\/terms-and-conditions\/"},"modified":"2023-05-23T16:45:34","modified_gmt":"2023-05-23T14:45:34","slug":"terms-and-conditions","status":"publish","type":"page","link":"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/","title":{"rendered":"Terms and Conditions"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"sticky_cta_settings":"","footnotes":""},"class_list":["post-1259","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u0161eobecn\u00e9 podm\u00ednky partnersk\u00e9ho programu eToro<\/title>\n<meta name=\"description\" content=\"Zjist\u011bte v\u00edce o v\u0161eobecn\u00fdch podm\u00ednk\u00e1ch \u00fa\u010dasti v partnersk\u00e9m programu eToro \u2013 jak funguje a jak\u00e1 pravidla v n\u011bm plat\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u0161eobecn\u00e9 podm\u00ednky partnersk\u00e9ho programu eToro\" \/>\n<meta property=\"og:description\" content=\"Zjist\u011bte v\u00edce o v\u0161eobecn\u00fdch podm\u00ednk\u00e1ch \u00fa\u010dasti v partnersk\u00e9m programu eToro \u2013 jak funguje a jak\u00e1 pravidla v n\u011bm plat\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/\" \/>\n<meta property=\"og:site_name\" content=\"eToro Partners\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-23T14:45:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/terms-and-conditions\\\/\",\"url\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/terms-and-conditions\\\/\",\"name\":\"V\u0161eobecn\u00e9 podm\u00ednky partnersk\u00e9ho programu eToro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/#website\"},\"datePublished\":\"2021-01-14T11:31:50+00:00\",\"dateModified\":\"2023-05-23T14:45:34+00:00\",\"description\":\"Zjist\u011bte v\u00edce o v\u0161eobecn\u00fdch podm\u00ednk\u00e1ch \u00fa\u010dasti v partnersk\u00e9m programu eToro \u2013 jak funguje a jak\u00e1 pravidla v n\u011bm plat\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/terms-and-conditions\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/etoropartners.com\\\/cs\\\/terms-and-conditions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/terms-and-conditions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u0160EOBECN\u00c9 OBCHODN\u00cd PODM\u00cdNKY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/#website\",\"url\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/\",\"name\":\"eToro Partners\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/etoropartners.com\\\/cs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u0161eobecn\u00e9 podm\u00ednky partnersk\u00e9ho programu eToro","description":"Zjist\u011bte v\u00edce o v\u0161eobecn\u00fdch podm\u00ednk\u00e1ch \u00fa\u010dasti v partnersk\u00e9m programu eToro \u2013 jak funguje a jak\u00e1 pravidla v n\u011bm plat\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/","og_locale":"cs_CZ","og_type":"article","og_title":"V\u0161eobecn\u00e9 podm\u00ednky partnersk\u00e9ho programu eToro","og_description":"Zjist\u011bte v\u00edce o v\u0161eobecn\u00fdch podm\u00ednk\u00e1ch \u00fa\u010dasti v partnersk\u00e9m programu eToro \u2013 jak funguje a jak\u00e1 pravidla v n\u011bm plat\u00ed.","og_url":"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/","og_site_name":"eToro Partners","article_modified_time":"2023-05-23T14:45:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/","url":"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/","name":"V\u0161eobecn\u00e9 podm\u00ednky partnersk\u00e9ho programu eToro","isPartOf":{"@id":"https:\/\/etoropartners.com\/cs\/#website"},"datePublished":"2021-01-14T11:31:50+00:00","dateModified":"2023-05-23T14:45:34+00:00","description":"Zjist\u011bte v\u00edce o v\u0161eobecn\u00fdch podm\u00ednk\u00e1ch \u00fa\u010dasti v partnersk\u00e9m programu eToro \u2013 jak funguje a jak\u00e1 pravidla v n\u011bm plat\u00ed.","breadcrumb":{"@id":"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/etoropartners.com\/cs\/terms-and-conditions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/etoropartners.com\/cs\/terms-and-conditions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/etoropartners.com\/cs\/"},{"@type":"ListItem","position":2,"name":"V\u0160EOBECN\u00c9 OBCHODN\u00cd PODM\u00cdNKY"}]},{"@type":"WebSite","@id":"https:\/\/etoropartners.com\/cs\/#website","url":"https:\/\/etoropartners.com\/cs\/","name":"eToro Partners","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/etoropartners.com\/cs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"}]}},"_links":{"self":[{"href":"https:\/\/etoropartners.com\/cs\/wp-json\/wp\/v2\/pages\/1259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etoropartners.com\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/etoropartners.com\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/etoropartners.com\/cs\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/etoropartners.com\/cs\/wp-json\/wp\/v2\/comments?post=1259"}],"version-history":[{"count":0,"href":"https:\/\/etoropartners.com\/cs\/wp-json\/wp\/v2\/pages\/1259\/revisions"}],"wp:attachment":[{"href":"https:\/\/etoropartners.com\/cs\/wp-json\/wp\/v2\/media?parent=1259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}